{"id":88555,"date":"2022-08-30T22:35:26","date_gmt":"2022-08-30T22:35:26","guid":{"rendered":"https:\/\/karinedana.com\/?p=88555"},"modified":"2024-04-15T12:01:55","modified_gmt":"2024-04-15T12:01:55","slug":"liberez-votre-cerveau","status":"publish","type":"post","link":"https:\/\/karinedana.com\/he\/liberez-votre-cerveau","title":{"rendered":"LIB\u00c9REZ VOTRE CERVEAU"},"content":{"rendered":"<h2><strong>LIB\u00c9REZ VOTRE CERVEAU<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-88556\" src=\"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-300x300.jpg 300w, https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-1024x1024.jpg 1024w, https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-150x150.jpg 150w, https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-768x768.jpg 768w, https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-1536x1536.jpg 1536w, https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-2048x2048.jpg 2048w, https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-scaled.jpg 2560w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>L\u2019organe le plus myst\u00e9rieux de notre anatomie, le plus complexe et mal compris est notre cerveau.<\/p>\n<p>Il est le disque dur de notre intelligence mais savons-nous vraiment quel syst\u00e8me d\u2019exploitation utiliser afin de tirer profit au mieux de nos capacit\u00e9s ?<\/p>\n<p>Utilisons-nous notre cerveau de fa\u00e7on ad\u00e9quate et performante ? Pourquoi certains sortent du lot, sont des prodiges, ont des capacit\u00e9s et des dons \u00e9blouissants\u00a0?Pourtant, nous avons tous le m\u00eame nombre de neurones, d\u2019aires et de synapses. Et si chacun de nous avait des capacit\u00e9s cach\u00e9es ou un don qu\u2019il ne soup\u00e7onnait pas\u00a0?<\/p>\n<p>Nos \u00e9coles sont-elles vraiment con\u00e7ues pour que nous puissions d\u00e9velopper au mieux nos potentiels\u00a0?<\/p>\n<p>Au cours du XIX\u00e8me si\u00e8cle un processus historique a fait basculer notre civilisation, cette transformation affectera profond\u00e9ment notre \u00e9cole, nos villes, la nature, l\u2019\u00e9conomie, le droit, la politique et tout le fonctionnement de notre soci\u00e9t\u00e9 dans son ensemble. Aucun domaine ne sera \u00e9pargn\u00e9. C\u2019est la r\u00e9volution industrielle.<\/p>\n<p>Ce mod\u00e8le industriel s\u2019impose tel une dictature partout.<\/p>\n<p>L\u2019exemple le plus terrible et le plus extr\u00eame est l\u2019industrialisation de la souffrance des animaux destin\u00e9s \u00e0 la consommation, car les industries des voitures, des v\u00eatements et autres objets ont mis ce mod\u00e8le au service d\u2019une industrie immorale, qui traite des \u00eatres vivants comme des choses, transforme les lieux d\u2019\u00e9levages en prisons et en salles de tortures \u00e0 grande \u00e9chelle.<\/p>\n<p>Le mod\u00e8le de l\u2019industrie se met \u00e9galement au service de l\u2019\u00e9cole et cr\u00e9e l\u2019industrialisation du savoir. Nos enfants doivent entrer dans des moules pr\u00e9cis conforment aux exigences de l\u2019\u00e9ducation nationale. Ceux qui ne s\u2019y soumettent pas, ceux qui ne peuvent pas s\u2019y soumettre, ceux qui refusent de s\u2019y soumettre sont mal consid\u00e9r\u00e9s ou exclu.<\/p>\n<p>L\u2019\u00e9cole, qui autrefois \u00e9tait un privil\u00e8ge tr\u00e8s convoit\u00e9, est devenue une corv\u00e9e, une source de stress, un lieu d\u2019\u00e9chec, un lieu de d\u2019exclusion, d\u2019\u00e9tiquetage, de gavage, de frustration. Chaque \u00e9l\u00e8ve est diff\u00e9rent et si le plaisir de l\u2019\u00e9cole \u00e9merge, cela n\u2019arrive que par accident car l\u2019\u00e9cole n\u2019est pas con\u00e7ue pour plaire et \u00e9merveiller, mais pour contraindre et conditionner.<\/p>\n<p>Nous sommes \u00e0 un carrefour, une grande place et plusieurs routes sont possible. Mais elles sont toutes sans issues, nous faisons le tour de la place m\u00e9thodiquement et plusieurs fois, dans l\u2019espoir de trouver enfin une route qui nous permettra d\u2019avancer vers une nouvelle direction.<\/p>\n<p>Soudain appara\u00eet un horizon nouveau, c\u2019est celui que d\u00e9veloppe\u00a0<strong>Idriss Aberkane <\/strong>dans son essai passionnant, publi\u00e9 en 2016,<\/p>\n<p><strong>Lib<\/strong><strong>\u00e9<\/strong><strong>rez votre cerveau\u00a0!\u00a0<\/strong><em>Trait<\/em><em>\u00e9<\/em><em> de neurosagesse pour changer l\u2019<\/em><em>\u00e9<\/em><em>cole et la soci<\/em><em>\u00e9<\/em><em>t<\/em><em>\u00e9<\/em><em>.<\/em><\/p>\n<p>Idriss Aberkane, n\u00e9 en 1986, est un enseignant, conf\u00e9rencier et essayiste fran\u00e7ais. Titulaire de plusieurs doctorats, il publie des chroniques dans le magazine Le Point et Huffington post. Tr\u00e8s pr\u00e9sent sur les r\u00e9seaux sociaux, il s\u2019exprime sur l\u2019\u00e9conomie de la connaissance. Son succ\u00e8s m\u00e9diatique attire \u00e9galement de vives critiques de la part des scientifiques. Son ouvrage ayant pour objectif la vulgarisation scientifique ne fait pas l\u2019unanimit\u00e9 parmi les chercheurs. Mais nous ne nous attarderons pas sur les descriptions physiologiques du cerveau ni sur ses positions controvers\u00e9es par ailleurs.<\/p>\n<p>Bien au-del\u00e0 de ceci, dans cet ouvrage il nous d\u00e9livre un message :<\/p>\n<p>\u00ab\u00a0Il ne faut pas forcer le cerveau \u00e0 ressembler \u00e0 notre \u00e9cole, il faut forcer notre \u00e9cole \u00e0 ressembler \u00e0 notre cerveau.\u00a0\u00bb<\/p>\n<p>Ce message remet en cause notre syst\u00e8me \u00e9ducatif et notre soci\u00e9t\u00e9.<\/p>\n<p>Il est d\u2019ailleurs probable que les critiques \u00e0 son \u00e9gard soient li\u00e9es \u00e0 ce fait. Pourtant ce message il n\u2019a pas \u00e9t\u00e9 le seul \u00e0 le crier.<\/p>\n<p>Carl Rogers dans \u00ab\u00a0Libert\u00e9 pour apprendre\u00a0\u00bb, 1969, pr\u00f4ne pour une r\u00e9forme de l\u2019institution scolaire afin qu\u2019elle cesse d\u2019\u00eatre un cadre rigide qui entrave l\u2019individu pour devenir au contraire un lieu qui permettrait aux \u00e9l\u00e8ves de se r\u00e9v\u00e9ler.<\/p>\n<p>Plusieurs autres grands p\u00e9dagogues ont marqu\u00e9 l\u2019histoire tels que Maria Montessori, dans les ann\u00e9es 1900, qui d\u00e9veloppe une nouvelle m\u00e9thode permettant aux \u00e9l\u00e8ves de devenir autonomes et s\u2019organiser seul. Selon une \u00e9tude publi\u00e9e par la revue Science en 2006, les capacit\u00e9s scolaires mais aussi sociales des enfants pass\u00e9s par cet enseignement sont meilleurs et ils obtiennent des r\u00e9sultats sup\u00e9rieurs lors des \u00e9valuations.<\/p>\n<p>De nombreuses initiatives locales existent avec diff\u00e9rentes m\u00e9thodes, toutes vont dans le sens d\u2019une plus grande autonomie des \u00e9l\u00e8ves, du travail en \u00e9quipe, des emplois du temps et cours \u00e0 la cartes.<\/p>\n<p>Le ma\u00eetre mot est toujours le m\u00eame, l\u2019\u00e9cole doit s\u2019adapter aux exigences de la vraie vie.<\/p>\n<p>Mais tout ceci est rest\u00e9 en sommeil, presque \u00e9touff\u00e9 et obstin\u00e9ment mis en marge de l\u2019\u00e9ducation conventionnelle.<\/p>\n<p>Pour d\u00e9signer l\u2019\u00e9cole Idriss Aberkane parle de \u00ab la vie not\u00e9e\u00a0\u00bb, dans laquelle il faut entrer dans un moule, rester \u00e0 sa place, se soumettre, travailler seul, ne pas suivre son c\u0153ur ni son intuition mais rester conforme.<\/p>\n<p>Il nous explique que nous n\u2019utilisons pas \u00ab\u00a0ergonomiquement\u00a0\u00bb notre cerveau.\u00a0\u00a0Faire de la neuroergonomie, c\u2019est l\u2019art de bien utiliser le cerveau humain.<\/p>\n<p>Notre cerveau a des articulations et des mouvements qu\u2019il peut ou pas faire, il a ses limites,\u00a0<strong>des empans<\/strong>. L\u2019empan de la main est la distance qui va du bout de notre pouce au bout de notre petit doigt main ouverte, il conditionne ce que l\u2019on peut saisir, mais pour saisir un objet trop grand ou trop lourd avec notre main nous utilisons une poign\u00e9e, nous pouvons utiliser des poign\u00e9es c\u2019est-\u00e0-dire des repr\u00e9sentations adapt\u00e9es pour soulever des id\u00e9es plus larges, des objets d\u2019\u00e9tudes. C\u2019est munir les notions abstraites \u00ab\u00a0d\u2019une poign\u00e9e intellectuelle \u00bb.<\/p>\n<p>Notre cerveau est conditionn\u00e9, inhib\u00e9, et en le d\u00e9sinhibant par l\u2019attraction et le plaisir, c\u2019est aussi \u00ab\u00a0donner la parole \u00e0 la bonne population de neurones.\u00a0\u00bb<\/p>\n<p>Idriss Aberkane d\u00e9veloppe la notion d\u2019\u00e9conomie de la connaissance, qui est l\u2019\u00e9change de savoir. L\u2019information, elle, est ponctuelle, mais le savoir est reproductible. \u00ab\u00a0Quand on partage un bien mat\u00e9riel, on le divise, quand on partage un bien immat\u00e9riel on le multiplie.\u00a0\u00bb<\/p>\n<p>Il utilise une m\u00e9taphore tr\u00e8s repr\u00e9sentative de l\u2019enseignement d\u2019aujourd\u2019hui.<\/p>\n<p>Imaginez que vous avez tr\u00e8s faim et que vous \u00eates invit\u00e9 \u00e0 un superbe buffet. Une multitude de mets tr\u00e8s vari\u00e9s, certains tr\u00e8s app\u00e9tissants, d\u2019autres un peu moins, mais vous vous imaginez d\u00e9j\u00e0 go\u00fbter \u00e0 tout et vous r\u00e9galer. C\u2019est le paradis. A pr\u00e9sent on vous annonce que vous devez manger tout ce qui est sur cette grande table en une heure et que chaque nourriture restante sera factur\u00e9e tr\u00e8s cher. Maintenant vous \u00eates en enfer\u00a0! La nourriture n\u2019a pas chang\u00e9, seulement la raison et la mani\u00e8re de la manger.<\/p>\n<p>A l\u2019\u00e9cole c\u2019est pareil, c\u2019est le restaurant du savoir avec lequel on gave les \u00e9l\u00e8ves qui doivent ingurgiter tout \u00e0 un rythme bien pr\u00e9cis et ceci sans tenir compte des particularit\u00e9s de chacun. L\u2019enseignement est standardis\u00e9, un m\u00eame rythme pour tous sans distinction.<\/p>\n<p>Et le plaisir dans tout \u00e7a\u00a0?<\/p>\n<p>Le syst\u00e8me de notation n\u2019est pas forc\u00e9ment en cause, car les jeux sont not\u00e9s avec des scores et pourtant les joueurs les r\u00e9clament. Nos \u00e9coles sont devenues \u00ab\u00a0des usines \u00e0 \u00e9duquer\u00a0\u00bb et l\u2019explosion des cas de d\u00e9ficits d\u2019attention, d\u2019hyperactivit\u00e9s et autres troubles du comportement sont la preuve que notre \u00e9cole et notre soci\u00e9t\u00e9 sont malades.\u00a0Pas nos \u00e9l\u00e8ves.<\/p>\n<p>Idriss Aberkane enfonce le couteau dans la plaie et nous dit\u00a0: \u00ab C\u2019est bien la nature des r\u00e9gimes totalitaires que de stigmatiser leurs dissidents. \u00bb<\/p>\n<p>Dans cet essai un fil conducteur est pr\u00e9sent du d\u00e9but \u00e0 la fin. C\u2019est l\u2019amour.\u00a0Car \u00ab\u00a0l\u2019\u00e9merveillement est le moteur de l\u2019apprentissage et de la d\u00e9couverte \u00bb.<\/p>\n<p>Nous pouvons tous \u00eatre extraordinaire, mais rien ne peut s\u2019atteindre sans passion. Pour \u00eatre excellent dans un domaine il faut acqu\u00e9rir des milliers d\u2019heures de pratique pour cette t\u00e2che qu\u2019elle soit physique ou mentale, mais sans amour cela devient une corv\u00e9e impossible \u00e0 accomplir. Ceux qui excellent dans un domaine sont des amoureux, des passionn\u00e9s.<\/p>\n<p>Donner \u00e0 nos enfants l\u2019app\u00e9tit du savoir, c\u2019est leur donner la cl\u00e9 de la r\u00e9ussite et cela ne peut se faire uniquement avec un syst\u00e8me \u00e9ducatif qui les valorise, les autonomise, les responsabilise, reconnait leurs diff\u00e9rences, leur apprend \u00e0 faire des choix, \u00e0 faire des exp\u00e9riences et des d\u00e9couvertes, leur permet de d\u00e9velopper leur personnalit\u00e9, de partager, d\u2019\u00e9changer, de valoriser les travaux de groupes. Les pr\u00e9parent \u00e0 la vraie vie.<\/p>\n<p>Une \u00e9cole en ad\u00e9quation avec la nature humaine, avec le fonctionnement de leurs corps, de leurs cerveaux, de leurs rythmes, de leurs go\u00fbts. Une \u00e9cole qui donne la place \u00e0 l\u2019intuition, au plaisir, \u00e0 l\u2019\u00e9panouissement. Qui fait de la diff\u00e9rence un enrichissement et un tr\u00e9sor, qui valorise l\u2019initiative, qui fait de l\u2019\u00e9chec un outil de perfectionnement, une chance.<\/p>\n<p>Une \u00e9cole qui fera d\u2019eux les b\u00e2tisseurs d\u2019une soci\u00e9t\u00e9 \u00e9quilibr\u00e9e et riche de savoir.<\/p>\n<p>\u00ab\u00a0Nous ne sommes pas l\u00e0 pour nous conformer \u00e0 une empreinte, mais pour laisser la n\u00f4tre.\u00a0\u00bb \u00a0Idriss Aberkane<\/p>\n<p>A lire absolument\u00a0!<\/p>\n<p>\u05d0\u05d5\u05d3\u05d5\u05ea\u05d9<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>LIB\u00c9REZ VOTRE CERVEAU &nbsp; L\u2019organe le plus myst\u00e9rieux de notre anatomie, le plus complexe et mal compris est notre cerveau. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":88556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-88555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LIB\u00c9REZ VOTRE CERVEAU - Karine Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karinedana.com\/he\/liberez-votre-cerveau\/\" \/>\n<meta property=\"og:locale\" content=\"he_IL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIB\u00c9REZ VOTRE CERVEAU - Karine Dana\" \/>\n<meta property=\"og:description\" content=\"LIB\u00c9REZ VOTRE CERVEAU &nbsp; L\u2019organe le plus myst\u00e9rieux de notre anatomie, le plus complexe et mal compris est notre cerveau. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karinedana.com\/he\/liberez-votre-cerveau\/\" \/>\n<meta property=\"og:site_name\" content=\"Karine Dana\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-30T22:35:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T12:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u05e0\u05db\u05ea\u05d1 \u05e2\u05dc \u05d9\u05d3\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u05d6\u05de\u05df \u05e7\u05e8\u05d9\u05d0\u05d4 \u05de\u05d5\u05e2\u05e8\u05da\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 \u05d3\u05e7\u05d5\u05ea\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau\"},\"author\":{\"name\":\"Karine\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/#\\\/schema\\\/person\\\/eef7a85fa2db3129e9f7ec495436d8d9\"},\"headline\":\"LIB\u00c9REZ VOTRE CERVEAU\",\"datePublished\":\"2022-08-30T22:35:26+00:00\",\"dateModified\":\"2024-04-15T12:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau\"},\"wordCount\":1631,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/karinedana.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/liberer-votre-cerveau-image-scaled.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"he-IL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau\",\"url\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau\",\"name\":\"LIB\u00c9REZ VOTRE CERVEAU - Karine Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/karinedana.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/liberer-votre-cerveau-image-scaled.jpg\",\"datePublished\":\"2022-08-30T22:35:26+00:00\",\"dateModified\":\"2024-04-15T12:01:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#breadcrumb\"},\"inLanguage\":\"he-IL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"he-IL\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#primaryimage\",\"url\":\"https:\\\/\\\/karinedana.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/liberer-votre-cerveau-image-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/karinedana.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/liberer-votre-cerveau-image-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Concept of open mind as a a deep mountain cliff shaped as a human head with a ladder leading to the outside towards a glowing sun as a psychology and mental health metaphor for spiritual discovery.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/liberez-votre-cerveau#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/karinedana.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIB\u00c9REZ VOTRE CERVEAU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/#website\",\"url\":\"https:\\\/\\\/karinedana.com\\\/\",\"name\":\"Karine Dana\",\"description\":\"Th\u00e9rapeute\",\"publisher\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karinedana.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"he-IL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/#organization\",\"name\":\"Karine Dana\",\"url\":\"https:\\\/\\\/karinedana.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"he-IL\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/karinedana.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/image-3.png\",\"contentUrl\":\"https:\\\/\\\/karinedana.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/image-3.png\",\"width\":210,\"height\":210,\"caption\":\"Karine Dana\"},\"image\":{\"@id\":\"https:\\\/\\\/karinedana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/karinedana.com\\\/#\\\/schema\\\/person\\\/eef7a85fa2db3129e9f7ec495436d8d9\",\"name\":\"Karine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"he-IL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f6b0b8aecfcf984c974a63b6b9064cc6684e9c9822177abedeed8f970f083f3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f6b0b8aecfcf984c974a63b6b9064cc6684e9c9822177abedeed8f970f083f3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f6b0b8aecfcf984c974a63b6b9064cc6684e9c9822177abedeed8f970f083f3?s=96&d=mm&r=g\",\"caption\":\"Karine\"},\"sameAs\":[\"https:\\\/\\\/karinedana.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIB\u00c9REZ VOTRE CERVEAU - Karine Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karinedana.com\/he\/liberez-votre-cerveau\/","og_locale":"he_IL","og_type":"article","og_title":"LIB\u00c9REZ VOTRE CERVEAU - Karine Dana","og_description":"LIB\u00c9REZ VOTRE CERVEAU &nbsp; L\u2019organe le plus myst\u00e9rieux de notre anatomie, le plus complexe et mal compris est notre cerveau. [&hellip;]","og_url":"https:\/\/karinedana.com\/he\/liberez-votre-cerveau\/","og_site_name":"Karine Dana","article_published_time":"2022-08-30T22:35:26+00:00","article_modified_time":"2024-04-15T12:01:55+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-scaled.jpg","type":"image\/jpeg"}],"author":"Karine","twitter_card":"summary_large_image","twitter_misc":{"\u05e0\u05db\u05ea\u05d1 \u05e2\u05dc \u05d9\u05d3":"Karine","\u05d6\u05de\u05df \u05e7\u05e8\u05d9\u05d0\u05d4 \u05de\u05d5\u05e2\u05e8\u05da":"8 \u05d3\u05e7\u05d5\u05ea"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karinedana.com\/liberez-votre-cerveau#article","isPartOf":{"@id":"https:\/\/karinedana.com\/liberez-votre-cerveau"},"author":{"name":"Karine","@id":"https:\/\/karinedana.com\/#\/schema\/person\/eef7a85fa2db3129e9f7ec495436d8d9"},"headline":"LIB\u00c9REZ VOTRE CERVEAU","datePublished":"2022-08-30T22:35:26+00:00","dateModified":"2024-04-15T12:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/karinedana.com\/liberez-votre-cerveau"},"wordCount":1631,"commentCount":0,"publisher":{"@id":"https:\/\/karinedana.com\/#organization"},"image":{"@id":"https:\/\/karinedana.com\/liberez-votre-cerveau#primaryimage"},"thumbnailUrl":"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-scaled.jpg","articleSection":["Uncategorized"],"inLanguage":"he-IL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karinedana.com\/liberez-votre-cerveau#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karinedana.com\/liberez-votre-cerveau","url":"https:\/\/karinedana.com\/liberez-votre-cerveau","name":"LIB\u00c9REZ VOTRE CERVEAU - Karine Dana","isPartOf":{"@id":"https:\/\/karinedana.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karinedana.com\/liberez-votre-cerveau#primaryimage"},"image":{"@id":"https:\/\/karinedana.com\/liberez-votre-cerveau#primaryimage"},"thumbnailUrl":"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-scaled.jpg","datePublished":"2022-08-30T22:35:26+00:00","dateModified":"2024-04-15T12:01:55+00:00","breadcrumb":{"@id":"https:\/\/karinedana.com\/liberez-votre-cerveau#breadcrumb"},"inLanguage":"he-IL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karinedana.com\/liberez-votre-cerveau"]}]},{"@type":"ImageObject","inLanguage":"he-IL","@id":"https:\/\/karinedana.com\/liberez-votre-cerveau#primaryimage","url":"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-scaled.jpg","contentUrl":"https:\/\/karinedana.com\/wp-content\/uploads\/2022\/08\/liberer-votre-cerveau-image-scaled.jpg","width":2560,"height":2560,"caption":"Concept of open mind as a a deep mountain cliff shaped as a human head with a ladder leading to the outside towards a glowing sun as a psychology and mental health metaphor for spiritual discovery."},{"@type":"BreadcrumbList","@id":"https:\/\/karinedana.com\/liberez-votre-cerveau#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/karinedana.com\/"},{"@type":"ListItem","position":2,"name":"LIB\u00c9REZ VOTRE CERVEAU"}]},{"@type":"WebSite","@id":"https:\/\/karinedana.com\/#website","url":"https:\/\/karinedana.com\/","name":"\u05d0\u05d5\u05d3\u05d5\u05ea\u05d9","description":"Th\u00e9rapeute","publisher":{"@id":"https:\/\/karinedana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karinedana.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"he-IL"},{"@type":"Organization","@id":"https:\/\/karinedana.com\/#organization","name":"\u05d0\u05d5\u05d3\u05d5\u05ea\u05d9","url":"https:\/\/karinedana.com\/","logo":{"@type":"ImageObject","inLanguage":"he-IL","@id":"https:\/\/karinedana.com\/#\/schema\/logo\/image\/","url":"https:\/\/karinedana.com\/wp-content\/uploads\/2021\/03\/image-3.png","contentUrl":"https:\/\/karinedana.com\/wp-content\/uploads\/2021\/03\/image-3.png","width":210,"height":210,"caption":"Karine Dana"},"image":{"@id":"https:\/\/karinedana.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/karinedana.com\/#\/schema\/person\/eef7a85fa2db3129e9f7ec495436d8d9","name":"Karine","image":{"@type":"ImageObject","inLanguage":"he-IL","@id":"https:\/\/secure.gravatar.com\/avatar\/1f6b0b8aecfcf984c974a63b6b9064cc6684e9c9822177abedeed8f970f083f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f6b0b8aecfcf984c974a63b6b9064cc6684e9c9822177abedeed8f970f083f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f6b0b8aecfcf984c974a63b6b9064cc6684e9c9822177abedeed8f970f083f3?s=96&d=mm&r=g","caption":"Karine"},"sameAs":["https:\/\/karinedana.com"]}]}},"_links":{"self":[{"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/posts\/88555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/comments?post=88555"}],"version-history":[{"count":4,"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/posts\/88555\/revisions"}],"predecessor-version":[{"id":88708,"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/posts\/88555\/revisions\/88708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/media\/88556"}],"wp:attachment":[{"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/media?parent=88555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/categories?post=88555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karinedana.com\/he\/wp-json\/wp\/v2\/tags?post=88555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}